{"id":116577,"date":"2016-08-19T14:58:30","date_gmt":"2016-08-19T07:58:30","guid":{"rendered":"http:\/\/vibizmedia.com\/?p=116577"},"modified":"2016-08-19T18:00:00","modified_gmt":"2016-08-19T11:00:00","slug":"oxford-street-jalan-perbelanjaan-tersibuk-di-eropa","status":"publish","type":"post","link":"https:\/\/www.vibizmedia.com\/index.php\/2016\/08\/19\/oxford-street-jalan-perbelanjaan-tersibuk-di-eropa\/","title":{"rendered":"Oxford Street, Jalan Perbelanjaan Tersibuk di Eropa"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":116579,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[312,76],"tags":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vibizmedia.com\/index.php\/2016\/08\/19\/oxford-street-jalan-perbelanjaan-tersibuk-di-eropa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oxford Street, Jalan Perbelanjaan Tersibuk di Eropa - Vibizmedia.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vibizmedia.com\/index.php\/2016\/08\/19\/oxford-street-jalan-perbelanjaan-tersibuk-di-eropa\/\" \/>\n<meta property=\"og:site_name\" content=\"Vibizmedia.com\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-19T07:58:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-08-19T11:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vibizmedia.com\/wp-content\/uploads\/2016\/08\/Oxford-Street-London.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vibizmediacom\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maruli Sinambela\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vibizmedia.com\/#website\",\"url\":\"https:\/\/www.vibizmedia.com\/\",\"name\":\"Vibizmedia.com\",\"description\":\"Business, Culture and Research\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vibizmedia.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.vibizmedia.com\/index.php\/2016\/08\/19\/oxford-street-jalan-perbelanjaan-tersibuk-di-eropa\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/www.vibizmedia.com\/wp-content\/uploads\/2016\/08\/Oxford-Street-London.jpg\",\"contentUrl\":\"https:\/\/www.vibizmedia.com\/wp-content\/uploads\/2016\/08\/Oxford-Street-London.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Ilustrasi: Oxford Street, London. FOTO : VIBIZMEDIA.COM\/VERA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vibizmedia.com\/index.php\/2016\/08\/19\/oxford-street-jalan-perbelanjaan-tersibuk-di-eropa\/#webpage\",\"url\":\"https:\/\/www.vibizmedia.com\/index.php\/2016\/08\/19\/oxford-street-jalan-perbelanjaan-tersibuk-di-eropa\/\",\"name\":\"Oxford Street, Jalan Perbelanjaan Tersibuk di Eropa - Vibizmedia.com\",\"isPartOf\":{\"@id\":\"https:\/\/www.vibizmedia.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vibizmedia.com\/index.php\/2016\/08\/19\/oxford-street-jalan-perbelanjaan-tersibuk-di-eropa\/#primaryimage\"},\"datePublished\":\"2016-08-19T07:58:30+00:00\",\"dateModified\":\"2016-08-19T11:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.vibizmedia.com\/#\/schema\/person\/a3c1e780f9f0fd72a0c3204e531635bb\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.vibizmedia.com\/index.php\/2016\/08\/19\/oxford-street-jalan-perbelanjaan-tersibuk-di-eropa\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vibizmedia.com\/index.php\/2016\/08\/19\/oxford-street-jalan-perbelanjaan-tersibuk-di-eropa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vibizmedia.com\/index.php\/2016\/08\/19\/oxford-street-jalan-perbelanjaan-tersibuk-di-eropa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.vibizmedia.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oxford Street, Jalan Perbelanjaan Tersibuk di Eropa\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.vibizmedia.com\/#\/schema\/person\/a3c1e780f9f0fd72a0c3204e531635bb\",\"name\":\"Maruli Sinambela\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.vibizmedia.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/584625cbe764860f367e0fe8164ec979?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/584625cbe764860f367e0fe8164ec979?s=96&d=mm&r=g\",\"caption\":\"Maruli Sinambela\"},\"description\":\"Maruli Sinambela is editor of vibizmedia.com and he is also a partner in management and technology services in Vibiz Consulting.\",\"sameAs\":[\"vibizmediacom\",\"https:\/\/twitter.com\/@vibizmediacom\"],\"url\":\"https:\/\/www.vibizmedia.com\/index.php\/author\/maruli\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vibizmedia.com\/index.php\/2016\/08\/19\/oxford-street-jalan-perbelanjaan-tersibuk-di-eropa\/","og_locale":"en_US","og_type":"article","og_title":"Oxford Street, Jalan Perbelanjaan Tersibuk di Eropa - Vibizmedia.com","og_url":"https:\/\/www.vibizmedia.com\/index.php\/2016\/08\/19\/oxford-street-jalan-perbelanjaan-tersibuk-di-eropa\/","og_site_name":"Vibizmedia.com","article_published_time":"2016-08-19T07:58:30+00:00","article_modified_time":"2016-08-19T11:00:00+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.vibizmedia.com\/wp-content\/uploads\/2016\/08\/Oxford-Street-London.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@vibizmediacom","twitter_misc":{"Written by":"Maruli Sinambela"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.vibizmedia.com\/#website","url":"https:\/\/www.vibizmedia.com\/","name":"Vibizmedia.com","description":"Business, Culture and Research","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vibizmedia.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/www.vibizmedia.com\/index.php\/2016\/08\/19\/oxford-street-jalan-perbelanjaan-tersibuk-di-eropa\/#primaryimage","inLanguage":"en-US","url":"https:\/\/www.vibizmedia.com\/wp-content\/uploads\/2016\/08\/Oxford-Street-London.jpg","contentUrl":"https:\/\/www.vibizmedia.com\/wp-content\/uploads\/2016\/08\/Oxford-Street-London.jpg","width":1280,"height":720,"caption":"Ilustrasi: Oxford Street, London. FOTO : VIBIZMEDIA.COM\/VERA"},{"@type":"WebPage","@id":"https:\/\/www.vibizmedia.com\/index.php\/2016\/08\/19\/oxford-street-jalan-perbelanjaan-tersibuk-di-eropa\/#webpage","url":"https:\/\/www.vibizmedia.com\/index.php\/2016\/08\/19\/oxford-street-jalan-perbelanjaan-tersibuk-di-eropa\/","name":"Oxford Street, Jalan Perbelanjaan Tersibuk di Eropa - Vibizmedia.com","isPartOf":{"@id":"https:\/\/www.vibizmedia.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vibizmedia.com\/index.php\/2016\/08\/19\/oxford-street-jalan-perbelanjaan-tersibuk-di-eropa\/#primaryimage"},"datePublished":"2016-08-19T07:58:30+00:00","dateModified":"2016-08-19T11:00:00+00:00","author":{"@id":"https:\/\/www.vibizmedia.com\/#\/schema\/person\/a3c1e780f9f0fd72a0c3204e531635bb"},"breadcrumb":{"@id":"https:\/\/www.vibizmedia.com\/index.php\/2016\/08\/19\/oxford-street-jalan-perbelanjaan-tersibuk-di-eropa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vibizmedia.com\/index.php\/2016\/08\/19\/oxford-street-jalan-perbelanjaan-tersibuk-di-eropa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vibizmedia.com\/index.php\/2016\/08\/19\/oxford-street-jalan-perbelanjaan-tersibuk-di-eropa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vibizmedia.com\/"},{"@type":"ListItem","position":2,"name":"Oxford Street, Jalan Perbelanjaan Tersibuk di Eropa"}]},{"@type":"Person","@id":"https:\/\/www.vibizmedia.com\/#\/schema\/person\/a3c1e780f9f0fd72a0c3204e531635bb","name":"Maruli Sinambela","image":{"@type":"ImageObject","@id":"https:\/\/www.vibizmedia.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/584625cbe764860f367e0fe8164ec979?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/584625cbe764860f367e0fe8164ec979?s=96&d=mm&r=g","caption":"Maruli Sinambela"},"description":"Maruli Sinambela is editor of vibizmedia.com and he is also a partner in management and technology services in Vibiz Consulting.","sameAs":["vibizmediacom","https:\/\/twitter.com\/@vibizmediacom"],"url":"https:\/\/www.vibizmedia.com\/index.php\/author\/maruli\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vibizmedia.com\/index.php\/wp-json\/wp\/v2\/posts\/116577"}],"collection":[{"href":"https:\/\/www.vibizmedia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vibizmedia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vibizmedia.com\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vibizmedia.com\/index.php\/wp-json\/wp\/v2\/comments?post=116577"}],"version-history":[{"count":1,"href":"https:\/\/www.vibizmedia.com\/index.php\/wp-json\/wp\/v2\/posts\/116577\/revisions"}],"predecessor-version":[{"id":116581,"href":"https:\/\/www.vibizmedia.com\/index.php\/wp-json\/wp\/v2\/posts\/116577\/revisions\/116581"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vibizmedia.com\/index.php\/wp-json\/wp\/v2\/media\/116579"}],"wp:attachment":[{"href":"https:\/\/www.vibizmedia.com\/index.php\/wp-json\/wp\/v2\/media?parent=116577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vibizmedia.com\/index.php\/wp-json\/wp\/v2\/categories?post=116577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vibizmedia.com\/index.php\/wp-json\/wp\/v2\/tags?post=116577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}